{"id":87,"date":"2010-12-24T20:14:42","date_gmt":"2010-12-24T19:14:42","guid":{"rendered":"https:\/\/english-munich.de\/blog\/?p=87"},"modified":"2011-06-24T06:34:22","modified_gmt":"2011-06-24T05:34:22","slug":"zu-schnell-in-usa","status":"publish","type":"post","link":"https:\/\/english-munich.de\/blog\/zu-schnell-in-usa\/","title":{"rendered":"Zu schnell in USA"},"content":{"rendered":"<p>W\u00e4hrend Deutschland, das Land, in welchem eigentlich alles bis auf den Millimeter reguliert ist, sich den Luxus einer nicht existierenden Geschwindigkeitsbegrenzung g\u00f6nnt, nehmen US Polizeibeamte die Einhaltung des Speed Limits  im Land der unbegrenzten M\u00f6glichkeiten offenbar sehr ernst.<\/p>\n<p><iframe width=\"425\" height=\"349\" src=\"http:\/\/www.youtube.com\/embed\/mJ_1XQOtiYg\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>W\u00e4hrend Deutschland, das Land, in welchem eigentlich alles bis auf den Millimeter reguliert ist, sich den Luxus einer nicht existierenden Geschwindigkeitsbegrenzung g\u00f6nnt, nehmen US Polizeibeamte die Einhaltung des Speed Limits im Land der unbegrenzten M\u00f6glichkeiten offenbar sehr ernst.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[7],"tags":[],"class_list":["post-87","post","type-post","status-publish","format-standard","hentry","category-interkulturelles"],"_links":{"self":[{"href":"https:\/\/english-munich.de\/blog\/wp-json\/wp\/v2\/posts\/87","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/english-munich.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/english-munich.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/english-munich.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/english-munich.de\/blog\/wp-json\/wp\/v2\/comments?post=87"}],"version-history":[{"count":6,"href":"https:\/\/english-munich.de\/blog\/wp-json\/wp\/v2\/posts\/87\/revisions"}],"predecessor-version":[{"id":1014,"href":"https:\/\/english-munich.de\/blog\/wp-json\/wp\/v2\/posts\/87\/revisions\/1014"}],"wp:attachment":[{"href":"https:\/\/english-munich.de\/blog\/wp-json\/wp\/v2\/media?parent=87"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/english-munich.de\/blog\/wp-json\/wp\/v2\/categories?post=87"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/english-munich.de\/blog\/wp-json\/wp\/v2\/tags?post=87"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}