{"id":4351,"date":"2013-03-16T21:08:23","date_gmt":"2013-03-16T20:08:23","guid":{"rendered":"https:\/\/english-munich.de\/blog\/?p=4351"},"modified":"2013-03-17T16:28:29","modified_gmt":"2013-03-17T15:28:29","slug":"st-patricks-day-painting-the-town-green","status":"publish","type":"post","link":"https:\/\/english-munich.de\/blog\/en\/st-patricks-day-painting-the-town-green\/","title":{"rendered":"St. Patricks Day &#8211; Painting the town green"},"content":{"rendered":"<p>Es ist interessant, dass der Mensch immer einen Anlass braucht, um sich zu betrinken.<\/p>\n<p>Der Schutzpatron Irlands, St. Patrick, der erste christliche Missionar, der sich in diese rauhe Gegend wagte,\u00a0 liefert mit seinen Todestag, dem 17. M\u00e4rz 481 oder 483, weltweit Millionen von Iren, irischst\u00e4mmigen US-Amerikanern und anderen Trinkern, einen Vorwand, sich so richtig die Kante zu geben.<\/p>\n<p>Um dem ganzen einen traditionellen Anstrich zu verleihen, f\u00e4rben zum Beispiel irischst\u00e4mmige, vom Reinheitsgebot befreite,\u00a0 Barbesitzer in den USA, an diesem Tag ihr Bier gr\u00fcn. Gr\u00fcn ist n\u00e4mlich die Farbe, die auf der Nationalflagge der Republik Irland, die katholische Mehrheit der Insel repr\u00e4sentiert.<\/p>\n<p>Apropos Farben: die Redewendung im Deutschen &#8222;<em>es so richtig krachen zu lassen<\/em>&#8220; entspricht im Englischen &#8222;<em>to paint the town red<\/em>&#8222;, was von der irischen Biermarke Guiness, f\u00fcr den St. Patrick&#8217;s Day kurzerhand zu &#8222;<em>to paint the town green<\/em>&#8220; umgem\u00fcnzt wurde.<\/p>\n<p>Die traditionelle Parade in M\u00fcnchen zu diesem Anlass, ist mit mehrern tausend Teilnehmern aus Irland, Schottland und England, die gr\u00f6\u00dfte in Kontinentaleuropa. In diesem Jahr ist sogar die Allianzarena zu Ehren des irischen Nationalfeiertages gr\u00fcn erleuchtet.<\/p>\n<p><iframe width=\"560\" height=\"315\" src=\"http:\/\/www.youtube.com\/embed\/lHsPIE39WPk\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>Es ist interessant, dass der Mensch immer einen Anlass braucht, um sich zu betrinken. Der Schutzpatron Irlands, St. Patrick, der erste christliche Missionar, der sich in diese rauhe Gegend wagte,\u00a0 liefert mit seinen Todestag, dem 17. M\u00e4rz 481 oder 483, weltweit Millionen von Iren, irischst\u00e4mmigen US-Amerikanern und anderen Trinkern, einen Vorwand, sich so richtig die [&hellip;]<\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[22,7],"tags":[],"class_list":["post-4351","post","type-post","status-publish","format-standard","hentry","category-idioms-redewendungen","category-interkulturelles"],"_links":{"self":[{"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/posts\/4351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/comments?post=4351"}],"version-history":[{"count":5,"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/posts\/4351\/revisions"}],"predecessor-version":[{"id":4357,"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/posts\/4351\/revisions\/4357"}],"wp:attachment":[{"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/media?parent=4351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/categories?post=4351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/tags?post=4351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}