{"id":1571,"date":"2011-11-18T16:45:27","date_gmt":"2011-11-18T15:45:27","guid":{"rendered":"https:\/\/english-munich.de\/blog\/?p=1571"},"modified":"2011-11-18T16:46:33","modified_gmt":"2011-11-18T15:46:33","slug":"pardon-my-french-franzosisches-englisch","status":"publish","type":"post","link":"https:\/\/english-munich.de\/blog\/en\/pardon-my-french-franzosisches-englisch\/","title":{"rendered":"Pardon My French &#8211; franz\u00f6sisches Englisch"},"content":{"rendered":"<p>George W Bush hat sich gelegentlich \u00fcber die Ignoranz der Franzosen beschwert, weil diese kein eigenes Wort f\u00fcr &#8222;<strong>entrepreneur<\/strong>&#8220; (= Unternehmer) haben. Leider hat er dabei vergessen, dass  diese Vokabel im Englischen ein Lehnwort ist, und seinen Ursprung im Franz\u00f6sischen hat.<\/p>\n<p>Um Fettn\u00e4pfchen vorzubeugen hier einige weitere Beispiele f\u00fcr &#8222;<strong>franz\u00f6sisches Englisch<\/strong>&#8222;:<\/p>\n<p>cache = Versteck<\/p>\n<p>cr\u00e8che = Kinderkrippe<\/p>\n<p>fianc\u00e9 = Verlobter, fianc\u00e9e = Verlobte<\/p>\n<p>gaffe = Fettn\u00e4pfchen<\/p>\n<p>fait accompli = vollendete Tatsachen<\/p>\n<p>forte = starke Seite<\/p>\n<p>Diese Worte werden nur auf gehobenem Sprachniveau verwendet, weswegen Sie im Alltagsgebrauch eigentlich vermieden werden sollten, um nicht gespreitzt zu klingen.<\/p>\n<p>Um einer Schimpftirade die Sch\u00e4rfe zu nehmen, f\u00fcgen Anglophone oft ironischerweise &#8222;<strong>pardon my French<\/strong>&#8220; an, was so viel wie &#8220; das musste jetzt aber mal gesagt werden&#8220; bedeutet.<\/p>","protected":false},"excerpt":{"rendered":"<p>George W Bush hat sich gelegentlich \u00fcber die Ignoranz der Franzosen beschwert, weil diese kein eigenes Wort f\u00fcr &#8222;entrepreneur&#8220; (= Unternehmer) haben. Leider hat er dabei vergessen, dass diese Vokabel im Englischen ein Lehnwort ist, und seinen Ursprung im Franz\u00f6sischen hat. Um Fettn\u00e4pfchen vorzubeugen hier einige weitere Beispiele f\u00fcr &#8222;franz\u00f6sisches Englisch&#8222;: cache = Versteck cr\u00e8che [&hellip;]<\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[3],"tags":[],"class_list":["post-1571","post","type-post","status-publish","format-standard","hentry","category-linguistics"],"_links":{"self":[{"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/posts\/1571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/comments?post=1571"}],"version-history":[{"count":3,"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/posts\/1571\/revisions"}],"predecessor-version":[{"id":1574,"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/posts\/1571\/revisions\/1574"}],"wp:attachment":[{"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/media?parent=1571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/categories?post=1571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/tags?post=1571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}