{"id":1,"date":"2010-12-09T20:47:59","date_gmt":"2010-12-09T19:47:59","guid":{"rendered":"https:\/\/english-munich.de\/blog\/?p=1"},"modified":"2010-12-18T09:46:56","modified_gmt":"2010-12-18T08:46:56","slug":"intro","status":"publish","type":"post","link":"https:\/\/english-munich.de\/blog\/en\/intro\/","title":{"rendered":"Hi there!"},"content":{"rendered":"<p>Welcome to <strong>Englisch f\u00fcr alle.<\/strong><\/p>\n<p><strong>Englisch f\u00fcr alle<\/strong> ist wie der Name dezent andeutet f\u00fcr alle da, und besonders f\u00fcr alle diejenigen, die sich f\u00fcr die englische Sprache, USA, GB und alles was es sonst noch mit diesem Thema zusammenh\u00e4ngt, interessieren.<\/p>\n<p>Der Blog ist unterteilt in f\u00fcnf Kategorien<\/p>\n<p><strong>Didactics:<\/strong> hier geht es um die Vermittlung von Wissen und Tips wie man am effektivsten Englisch lernt. Ich m\u00f6chte hier Lernenden meine jahrelange Erfahrung und Praxis in diesem Bereich weitergeben, um den Lernprozess interessanter und farbiger zu gestalten<\/p>\n<p><strong>Englisch in M\u00fcnchen:<\/strong> diese Kategorie soll den Blogger mit Info \u00fcber Events und Locations auf dem Laufenden halten, die mit Englisch zu tun haben.<\/p>\n<p><strong>Laugh On the Loser:<\/strong> auch der Humor soll nicht zu kurz kommen, hier soll das Hauptaugenmerk auf der komischen Seite liegen, die man nicht selten dem Aufeinandertreffen der angloamerikanischen\u00a0 und der deutschen Kultur abgewinnen kann.<\/p>\n<p><strong>Lingusitics<\/strong>: lingusitics soll helfen den Lernden mit Tips und Tricks zu unterst\u00fctzen um ein ideomatischeres stilsichereres Englisch zu sprechen und zu schreiben.<\/p>\n<p><strong>Interkulturelles:<\/strong> In dieser Kategorie geht es um Anregungen im Bezug auf Probleme des deutsch angloamerikanischen Miteinander.<\/p>\n<p><strong>News: <\/strong>hier kannst Du Informationen rund um die Website <strong>http:\/\/www.english-munich.de<\/strong> erhalten. Die massgebliche Site f\u00fcr alles was Englisch lernen angeht.<\/p>\n<p>Da der Blog noch ziemliche neu ist, gibt es hier sicherlich noch Raum f\u00fcr Entwicklung. Vorschl\u00e4ge und Beitr\u00e4ge sind immer willkommen.<\/p>\n<p>ok let\u00b4s rock<\/p>\n<p><strong>IMPRESSUM<\/strong><\/p>\n<p>verantwortlich f\u00fcr den Inhalt der Seite:<\/p>\n<p>Franz Seidenfu\u00df<\/p>\n<p>Camerloherstr. 24<\/p>\n<p>80686 M\u00fcnchen<\/p>\n<p>info@english-munich.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Welcome to Englisch f\u00fcr alle. Englisch f\u00fcr alle ist wie der Name dezent andeutet f\u00fcr alle da, und besonders f\u00fcr alle diejenigen, die sich f\u00fcr die englische Sprache, USA, GB und alles was es sonst noch mit diesem Thema zusammenh\u00e4ngt, interessieren. Der Blog ist unterteilt in f\u00fcnf Kategorien Didactics: hier geht es um die Vermittlung [&hellip;]<\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-1","post","type-post","status-publish","format-standard","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/posts\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/comments?post=1"}],"version-history":[{"count":7,"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/posts\/1\/revisions"}],"predecessor-version":[{"id":10,"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/posts\/1\/revisions\/10"}],"wp:attachment":[{"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/media?parent=1"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/categories?post=1"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/english-munich.de\/blog\/en\/wp-json\/wp\/v2\/tags?post=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}